{"id":9877,"date":"2018-05-25T09:00:49","date_gmt":"2018-05-25T07:00:49","guid":{"rendered":"http:\/\/greth.fr\/?p=9877"},"modified":"2023-02-23T16:46:19","modified_gmt":"2023-02-23T15:46:19","slug":"etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/","title":{"rendered":"\u00c9tude hydraulique et thermique d&#8217;un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles"},"content":{"rendered":"<p><strong><span style=\"text-decoration: underline;\">Summary :<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Cette th\u00e8se contribue aux avanc\u00e9es dans la conception, la fabrication, l\u2019exp\u00e9rimentation ainsi que l\u2019optimisation de r\u00e9seaux fluides multi-\u00e9chelles. Ces r\u00e9seaux permettent de g\u00e9rer des d\u00e9bits importants tout en gagnant en compacit\u00e9 ainsi qu\u2019en intensifiant les transferts de masse et d\u2019\u00e9nergie par l\u2019augmentation de la surface active. La structure interne du r\u00e9seau multi- \u00e9chelles \u00e9tudi\u00e9 est optimis\u00e9e en diminuant les pertes de charges par la mise en parall\u00e8les des micro\/minicanaux. Des prototypes en aluminium et en PMMA ont \u00e9t\u00e9 fabriqu\u00e9s au sein du LTEN par gravure gr\u00e2ce \u00e0 une commande num\u00e9rique. Les prototypes ont \u00e9t\u00e9 test\u00e9s afin d\u2019\u00e9valuer le comportement du fluide \u00e0 l\u2019int\u00e9rieur ainsi que ses performances thermiques, par simulations num\u00e9riques (CFD) et par des dispositifs exp\u00e9rimentaux (PIV, Cam\u00e9ra Rapide, Thermocouples). A \u00e9t\u00e9 test\u00e9 l\u2019influence de la g\u00e9om\u00e9trie du distributeur\/collecteur sur la distribution du fluide, puis, du fait de la perte de compacit\u00e9, a \u00e9t\u00e9 choisi  l\u2019insertion de plaques perfor\u00e9es optimis\u00e9es dans les diff\u00e9rents distributeurs du r\u00e9seau.  L\u2019uniformisation de la distribution permet d\u2019augmenter les performances thermiques d\u2019environ 10 %. Suite \u00e0 ces r\u00e9sultats une conception d\u2019\u00e9changeur de chaleur \u00e0 plaques a \u00e9t\u00e9 r\u00e9alis\u00e9e, par simulations num\u00e9riques (CFD) et par la mise en place d\u2019un banc d\u2019essais. Les performances ont \u00e9t\u00e9 test\u00e9es sous diff\u00e9rentes conditions.<\/p>\n<table width=\"100%\" border=\"1\">\n<tr>\n<td><strong>Author<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Cyril PISTORESI<\/td>\n<\/tr>\n<tr>\n<td><strong>Date de publication<\/strong><\/td>\n<\/tr>\n<tr>\n<td>10 avril 2017<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>\u00c9changeur de chaleur, Multi-\u00e9chelles, Distribution, Transfert Thermiques, Micro\/Mini-canaux, PIV, Cam\u00e9ra Rapide<\/td>\n<\/tr>\n<\/table>\n\n&nbsp;<br \/>\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 : Cette th\u00e8se contribue aux avanc\u00e9es dans la conception, la fabrication, l\u2019exp\u00e9rimentation ainsi que l\u2019optimisation de r\u00e9seaux fluides multi-\u00e9chelles. Ces r\u00e9seaux permettent de g\u00e9rer des d\u00e9bits importants tout en gagnant en compacit\u00e9 ainsi qu\u2019en intensifiant les transferts de masse et d\u2019\u00e9nergie par l\u2019augmentation de la surface active. La structure interne du r\u00e9seau multi- \u00e9chelles &hellip;<\/p>","protected":false},"author":1,"featured_media":961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,21],"tags":[],"class_list":["post-9877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents","category-memoires-theses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9tude hydraulique et thermique d&#039;un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tude hydraulique et thermique d&#039;un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 : Cette th\u00e8se contribue aux avanc\u00e9es dans la conception, la fabrication, l\u2019exp\u00e9rimentation ainsi que l\u2019optimisation de r\u00e9seaux fluides multi-\u00e9chelles. Ces r\u00e9seaux permettent de g\u00e9rer des d\u00e9bits importants tout en gagnant en compacit\u00e9 ainsi qu\u2019en intensifiant les transferts de masse et d\u2019\u00e9nergie par l\u2019augmentation de la surface active. La structure interne du r\u00e9seau multi- \u00e9chelles &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-25T07:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-23T15:46:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"\u00c9tude hydraulique et thermique d&#8217;un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles\",\"datePublished\":\"2018-05-25T07:00:49+00:00\",\"dateModified\":\"2023-02-23T15:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/\"},\"wordCount\":657,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-5.jpg\",\"articleSection\":[\"Documents\",\"M\u00e9moires de th\u00e8ses\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/\",\"name\":\"\u00c9tude hydraulique et thermique d'un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-5.jpg\",\"datePublished\":\"2018-05-25T07:00:49+00:00\",\"dateModified\":\"2023-02-23T15:46:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-5.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-5.jpg\",\"width\":424,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9tude hydraulique et thermique d&#8217;un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9tude hydraulique et thermique d'un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/","og_locale":"en_US","og_type":"article","og_title":"\u00c9tude hydraulique et thermique d'un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles","og_description":"R\u00e9sum\u00e9 : Cette th\u00e8se contribue aux avanc\u00e9es dans la conception, la fabrication, l\u2019exp\u00e9rimentation ainsi que l\u2019optimisation de r\u00e9seaux fluides multi-\u00e9chelles. Ces r\u00e9seaux permettent de g\u00e9rer des d\u00e9bits importants tout en gagnant en compacit\u00e9 ainsi qu\u2019en intensifiant les transferts de masse et d\u2019\u00e9nergie par l\u2019augmentation de la surface active. La structure interne du r\u00e9seau multi- \u00e9chelles &hellip;","og_url":"https:\/\/greth.fr\/en\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2018-05-25T07:00:49+00:00","article_modified_time":"2023-02-23T15:46:19+00:00","og_image":[{"width":424,"height":283,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-5.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"\u00c9tude hydraulique et thermique d&#8217;un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles","datePublished":"2018-05-25T07:00:49+00:00","dateModified":"2023-02-23T15:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/"},"wordCount":657,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-5.jpg","articleSection":["Documents","M\u00e9moires de th\u00e8ses"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/","url":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/","name":"\u00c9tude hydraulique et thermique d'un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-5.jpg","datePublished":"2018-05-25T07:00:49+00:00","dateModified":"2023-02-23T15:46:19+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-5.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-5.jpg","width":424,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/etude-hydraulique-et-thermique-dun-echangeur-de-chaleur-a-plaques-a-structure-multi-echelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9tude hydraulique et thermique d&#8217;un \u00e9changeur de chaleur \u00e0 plaques \u00e0 structure multi-\u00e9chelles"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/9877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=9877"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/9877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/961"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=9877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=9877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=9877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}