{"id":3411,"date":"2005-01-25T16:00:37","date_gmt":"2005-01-25T15:00:37","guid":{"rendered":"http:\/\/greth.fr\/?p=3411"},"modified":"2015-10-28T16:11:35","modified_gmt":"2015-10-28T15:11:35","slug":"les-emplois-de-lecologie","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/les-emplois-de-lecologie\/","title":{"rendered":"Les Emplois de l\u2019\u00c9cologie"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3412\" src=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg\" alt=\"Ecologie - 01\" width=\"397\" height=\"302\" srcset=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg 397w, https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01-88x67.jpg 88w, https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01-300x228.jpg 300w\" sizes=\"auto, (max-width: 397px) 100vw, 397px\" \/><\/a><\/p>\n<p>20 millions d'euros pour le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s de l'Environnement<\/p>\n<p>Le minist\u00e8re de l\u2019\u00e9cologie et du D\u00e9veloppement durable mobilise, en 2005, 20 millions d'euros pour soutenir les projets des PME-PMI dans le domaine de l'environnement et du d\u00e9veloppement durable, en finan\u00e7ant le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s pour ces m\u00e9tiers.<\/p>\n<p>Ce dispositif innovant, qui sera instruit par les DRIRE avec l'appui de l'<a href=\"http:\/\/ www.ademe.fr\/\" target=\"_blank\">ADEME<\/a> et des Chambres de Commerce et d'Industrie, constitue un facteur de progr\u00e8s significatif :<\/p>\n<p>- pour la comp\u00e9titivit\u00e9 et l'emploi des PME-PMI gr\u00e2ce aux opportunit\u00e9s que la g\u00e9n\u00e9ralisation des strat\u00e9gies environnementales leur permettra de d\u00e9velopper aupr\u00e8s de leurs clients et fournisseurs.<\/p>\n<p>- pour le d\u00e9veloppement des formations sup\u00e9rieures et de leurs d\u00e9bouch\u00e9s dans les m\u00e9tiers de l'\u00e9cologie, du management environnemental et de la gestion durable.<\/p>\n<p>- pour l'am\u00e9lioration de la qualit\u00e9 globale de l'environnement dans notre pays.<\/p>\n<p>Liens \u00e0 consulter :<br \/>\n- <a href=\"http:\/\/www1.environnement.gouv.fr\/article.php3?id_article=3469\" target=\"_blank\">http:\/\/www1.environnement.gouv.fr\/article.php3?id_article=3469<\/a><br \/>\n- <a href=\"http:\/\/www1.environnement.gouv.fr\/IMG\/pdf\/emplois_ecologie_110105.pdf\" target=\"_blank\">http:\/\/www1.environnement.gouv.fr\/IMG\/pdf\/emplois_ecologie_110105.pdf<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>20 millions d&#8217;euros pour le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s de l&#8217;Environnement Le minist\u00e8re de l\u2019\u00e9cologie et du D\u00e9veloppement durable mobilise, en 2005, 20 millions d&#8217;euros pour soutenir les projets des PME-PMI dans le domaine de l&#8217;environnement et du d\u00e9veloppement durable, en finan\u00e7ant le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s pour ces m\u00e9tiers. Ce &hellip;<\/p>","protected":false},"author":1,"featured_media":3412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-du-greth"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Emplois de l\u2019\u00c9cologie - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/les-emplois-de-lecologie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Emplois de l\u2019\u00c9cologie\" \/>\n<meta property=\"og:description\" content=\"20 millions d&#039;euros pour le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s de l&#039;Environnement Le minist\u00e8re de l\u2019\u00e9cologie et du D\u00e9veloppement durable mobilise, en 2005, 20 millions d&#039;euros pour soutenir les projets des PME-PMI dans le domaine de l&#039;environnement et du d\u00e9veloppement durable, en finan\u00e7ant le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s pour ces m\u00e9tiers. Ce &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/les-emplois-de-lecologie\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2005-01-25T15:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-28T15:11:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"397\" \/>\n\t<meta property=\"og:image:height\" content=\"302\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"Les Emplois de l\u2019\u00c9cologie\",\"datePublished\":\"2005-01-25T15:00:37+00:00\",\"dateModified\":\"2015-10-28T15:11:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/ecologie-01.jpg\",\"articleSection\":[\"Les actualit\u00e9s du GRETh\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/\",\"name\":\"Les Emplois de l\u2019\u00c9cologie - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/ecologie-01.jpg\",\"datePublished\":\"2005-01-25T15:00:37+00:00\",\"dateModified\":\"2015-10-28T15:11:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/ecologie-01.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/ecologie-01.jpg\",\"width\":397,\"height\":302},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/les-emplois-de-lecologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Emplois de l\u2019\u00c9cologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Emplois de l\u2019\u00c9cologie - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/les-emplois-de-lecologie\/","og_locale":"en_US","og_type":"article","og_title":"Les Emplois de l\u2019\u00c9cologie","og_description":"20 millions d'euros pour le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s de l'Environnement Le minist\u00e8re de l\u2019\u00e9cologie et du D\u00e9veloppement durable mobilise, en 2005, 20 millions d'euros pour soutenir les projets des PME-PMI dans le domaine de l'environnement et du d\u00e9veloppement durable, en finan\u00e7ant le recrutement de 1000 jeunes cadres dipl\u00f4m\u00e9s pour ces m\u00e9tiers. Ce &hellip;","og_url":"https:\/\/greth.fr\/en\/les-emplois-de-lecologie\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2005-01-25T15:00:37+00:00","article_modified_time":"2015-10-28T15:11:35+00:00","og_image":[{"width":397,"height":302,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"Les Emplois de l\u2019\u00c9cologie","datePublished":"2005-01-25T15:00:37+00:00","dateModified":"2015-10-28T15:11:35+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/"},"wordCount":202,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg","articleSection":["Les actualit\u00e9s du GRETh"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/","url":"https:\/\/greth.fr\/les-emplois-de-lecologie\/","name":"Les Emplois de l\u2019\u00c9cologie - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg","datePublished":"2005-01-25T15:00:37+00:00","dateModified":"2015-10-28T15:11:35+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/les-emplois-de-lecologie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/10\/ecologie-01.jpg","width":397,"height":302},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/les-emplois-de-lecologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"Les Emplois de l\u2019\u00c9cologie"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/3411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=3411"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/3411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/3412"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=3411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=3411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=3411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}