{"id":21053,"date":"2024-08-19T11:00:41","date_gmt":"2024-08-19T09:00:41","guid":{"rendered":"https:\/\/greth.fr\/?p=21053"},"modified":"2025-10-27T17:11:21","modified_gmt":"2025-10-27T16:11:21","slug":"analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/","title":{"rendered":"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l&#8217;am\u00e9lioration de l&#8217;efficacit\u00e9 des machines \u00e0 absorption"},"content":{"rendered":"<strong><span style=\"text-decoration: underline;\">Summary:<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">In the context of greenhouse gases reduction, an increasing attention is dedicated to carbon\u2013free power plants solutions. To answer to this growing demand, tiny nuclear reactors or Small Modular Reactors (SMR), are being developed such as the 170Mwe Pressurized Water Reactor within the NUWARD project. This technology is downscaled, modular, with a very compact Steam Generators (SG) design in comparison to current recirculating SG. Moreover, the secondary fluid is vaporized through one unique passage in millimetric channels. However, such devices potentially include static (Ledinegg) and dynamic (density wave oscillations, \u2026) two-phase flow instabilities. These instabilities can alter the SG\u2019s efficiency, lifetime, and even integrity from modifying the temperature, mass flow and pressure levels. Consequently, it justifies a more precise analysis and understanding of the instability\u2019s mechanism. In this PhD, a thorough study of the Ledinegg instability and the flow maldistribution phenomenon is carried out in the compact plates SG\u2019s operating conditions. In a capillary dominated regime we consider a localized, infinitesimally thin interfacial front plunged into a forced longitudinal temperature gradient whereby vaporization arises leading to successive liquid-gas phases distribution within the channel. Whereas the liquid and vapor velocity profiles are provided by the Poiseuille\u2019s law, the temperature fields in the solid and the fluid are obtained using the generalized Graetz modes method, specifically adapted to the considered vaporization model. The generalized Graetz modes decomposition permits a semi-analytical solution of the 3D convection-diffusion problems provided that the velocity field, domain\u2019s section and Peclet\u2019s number are longitudinally invariant along the flow direction. In the first chapter, this methodology is used to analyse heat transfers in single-phase natural convection circulation loop. A new universal scaling law for the relation between the Grashof and the Reynolds numbers is obtained, this is confirmed by an asymptotic analysis and direct numerical simulations and is successfully compared with experimental data sets. This analysis has highlighted the influence of boundary conditions, boundary layers, and fluid to solid thermal conductivity ratio in the heat transfer control. In the second chapter, the generalized Graetz modes method is extended to solve the temperature fields as well as the two-phase interface position within the vaporization model. This methodology is applied to two configurations: a uniformly heated single channel and a co-current heat exchanger. The vaporization\u2019s numerical computation with imposed heat flux in a microchannel depicts the proportionality between the front\u2019s position and the liquid Peclet\u2019s number. The results are consistent with the theoretical energy balance analysis as well as with experimental data obtained in the literature for moderated mass flows and heating powers. Using the resulting interface\u2019s position law into a pressure drops model, the boundaries of the stability areas in a single heated microchannel and many parallel channels have been computed and analysed. In the case of the co-current heat exchanger, the state-of-the-art remains spotty because most of stability studies deals with imposed heat flux and thermally insulated channels, not relevant for conjugated heat transfers in a heat exchanger which deviate from such simplified assumptions. Our confined vaporization model predicts a logarithmic dependence between the two-phase interface\u2019s position and the secondary inlet Peclet\u2019s number. The influence of the fluid properties, primary mass flow and the wall thermal conductivity on this law has been studied and allowed to specify the stability criteria for a single heat exchanger and a network composed of parallel heat exchangers, closer to the compact plates\u2019 SG.<\/p>\n<table border=\"1\" width=\"100%\">\n<tbody>\n<tr>\n<td><strong>Author<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Arnat MAHAMOUDOU<\/td>\n<\/tr>\n<tr>\n<td><strong>Date of presentation<\/strong><\/td>\n<\/tr>\n<tr>\n<td>2024, march 8th<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Falling film, Entropy generation, Local and overall analysis, Absorber, Evaporator, Absorption machines<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 : L&#8217;augmentation de la demande d&#8217;\u00e9nergie est principalement due \u00e0 l&#8217;augmentation de la consommation d&#8217;\u00e9nergie dans les secteurs du b\u00e2timent et du tertiaire o\u00f9 20% de la consommation d&#8217;\u00e9nergie est consacr\u00e9e \u00e0 la climatisation en raison de l&#8217;augmentation de la temp\u00e9rature moyenne mondiale de 1\u00b0C. Or, l&#8217;utilisation des appareils de chauffage et de climatisation conventionnels a un impact consid\u00e9rable sur l&#8217;environnement car ils contribuent au r\u00e9chauffement climatique. Agir dans le secteur du b\u00e2timent en produisant du froid et de la chaleur bas carbone permettrait de r\u00e9duire consid\u00e9rablement son impact environnemental.Ces derni\u00e8res ann\u00e9es, les syst\u00e8mes \u00e0 sorption ont suscit\u00e9 l&#8217;int\u00e9r\u00eat de la communaut\u00e9 scientifique en raison de leur bonne efficacit\u00e9 \u00e9nerg\u00e9tique, haute densit\u00e9 \u00e9nerg\u00e9tique, de leurs faibles pertes de chaleur et de leur utilisation potentielle pour le stockage de l&#8217;\u00e9nergie solaire pendant les p\u00e9riodes saisonni\u00e8res. Les syst\u00e8mes \u00e0 absorption, en particulier, semblent \u00eatre une bonne alternative \u00e0 la compression m\u00e9canique des syst\u00e8mes de r\u00e9frig\u00e9ration standards pour diff\u00e9rentes raisons. Le fonctionnement de ces machines thermodynamiques est bas\u00e9 sur la mise en oeuvre de diff\u00e9rents \u00e9changeurs de chaleur et de masse (absorbeur, d\u00e9sorbeur, \u00e9vaporateur et condenseur). L&#8217;objectif de ce projet de recherche est de caract\u00e9riser en d\u00e9tail les ph\u00e9nom\u00e8nes de transferts coupl\u00e9s de masse et de chaleur, non seulement \u00e0 l&#8217;\u00e9chelle locale mais aussi \u00e0 l\u2019\u00e9chelle du composant, l\u2019\u00e9changeur le plus critique et le moins connu des machines \u00e0 absorption \u00e0 savoir l&#8217;absorbeur. L&#8217;approche adopt\u00e9e est bas\u00e9e sur l&#8217;analyse thermodynamique de ces \u00e9changeurs, selon les d\u00e9veloppements r\u00e9cents de la Thermodynamique des Processus Irr\u00e9versibles (TIP), dans le but d&#8217;identifier les diff\u00e9rentes sources d&#8217;irr\u00e9versibilit\u00e9s responsables d&#8217;une d\u00e9gradation des performances globales du syst\u00e8me.Le chapitre I pr\u00e9sente un \u00e9tat de l&#8217;art des mod\u00e8les de transferts coupl\u00e9s de chaleur et de masse et des applications de la thermodynamique des processus irr\u00e9versibles \u00e0 l\u2019absorbeur, afin de comprendre les principales hypoth\u00e8ses et les limites des diff\u00e9rents mod\u00e8les. Pour une meilleure compr\u00e9hension des sources d\u2019irr\u00e9versibilit\u00e9s dans les \u00e9changeurs simples, le chapitre II est consacr\u00e9 \u00e0 l&#8217;\u00e9tude d&#8217;un \u00e9vaporateur avant d\u2019introduire les ph\u00e9nom\u00e8nes plus complexes observ\u00e9s dans l\u2019absorbeur. Les bilans thermiques du fluide caloporteur et du film sont r\u00e9solus simultan\u00e9ment \u00e0 travers un mod\u00e8le 2D utilisant un sch\u00e9ma implicite de diff\u00e9rences finies. Des analyses locale et globale ont \u00e9t\u00e9 r\u00e9alis\u00e9es afin d&#8217;\u00e9tudier l&#8217;impact de param\u00e8tres tels que les nombres de Reynolds du fluide caloporteur et du film mais aussi la temp\u00e9rature du film en entr\u00e9e sur la cr\u00e9ation d&#8217;entropie (irr\u00e9versibilit\u00e9s thermique et visqueuse) et sur les efficacit\u00e9s thermique et d&#8217;\u00e9vaporation pour les configurations \u00e0 co et contre-courant. Le chapitre III d\u00e9veloppe un mod\u00e8le 2D d&#8217;absorbeur. Afin d&#8217;\u00e9tudier le cas r\u00e9el de l&#8217;absorbeur, le fluide caloporteur est suppos\u00e9 s&#8217;\u00e9couler \u00e0 contre-courant et diff\u00e9rents r\u00e9gimes d&#8217;\u00e9coulement du fluide caloporteur sont \u00e9tudi\u00e9s et compar\u00e9s aux cas limites &#8211; parois adiabatique et isotherme. Une formulation locale de la cr\u00e9ation d&#8217;entropie est propos\u00e9e pour identifier les diff\u00e9rentes sources d&#8217;irr\u00e9versibilit\u00e9s dans le but de les localiser et de les quantifier. Le chapitre IV permet une analyse globale du comportement des diff\u00e9rentes sources de cr\u00e9ation d&#8217;entropie en consid\u00e9rant diff\u00e9rentes conditions de fonctionnement. Le facteur d&#8217;\u00e9quilibre est introduit pour \u00e9tudier l&#8217;impact des d\u00e9bits du fluide caloporteur et du film sur le d\u00e9bit massique absorb\u00e9, le flux transf\u00e9r\u00e9 et la cr\u00e9ation d&#8217;entropie. Une optimisation multi-objectifs est \u00e9galement r\u00e9alis\u00e9e. Deux approches d&#8217;optimisation ont \u00e9t\u00e9 utilis\u00e9es afin de d\u00e9terminer le front de Pareto et de valider les solutions optimales.<\/p>","protected":false},"author":1,"featured_media":100,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,21],"tags":[6869,6861,6871,6860,6865,6867,6862,6870,6866,6864,6868,6863],"class_list":["post-21053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents","category-memoires-theses","tag-absorber","tag-absorbeur","tag-absorption-machines","tag-analyses-locale-et-globale","tag-creation-dentropie","tag-entropy-generation","tag-evaporateur","tag-evaporator","tag-falling-film","tag-film-tombant","tag-local-and-overall-analysis","tag-machines-a-absorption"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l&#039;am\u00e9lioration de l&#039;efficacit\u00e9 des machines \u00e0 absorption - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l&#039;am\u00e9lioration de l&#039;efficacit\u00e9 des machines \u00e0 absorption\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 : L&#039;augmentation de la demande d&#039;\u00e9nergie est principalement due \u00e0 l&#039;augmentation de la consommation d&#039;\u00e9nergie dans les secteurs du b\u00e2timent et du tertiaire o\u00f9 20% de la consommation d&#039;\u00e9nergie est consacr\u00e9e \u00e0 la climatisation en raison de l&#039;augmentation de la temp\u00e9rature moyenne mondiale de 1\u00b0C. Or, l&#039;utilisation des appareils de chauffage et de climatisation conventionnels a un impact consid\u00e9rable sur l&#039;environnement car ils contribuent au r\u00e9chauffement climatique. Agir dans le secteur du b\u00e2timent en produisant du froid et de la chaleur bas carbone permettrait de r\u00e9duire consid\u00e9rablement son impact environnemental.Ces derni\u00e8res ann\u00e9es, les syst\u00e8mes \u00e0 sorption ont suscit\u00e9 l&#039;int\u00e9r\u00eat de la communaut\u00e9 scientifique en raison de leur bonne efficacit\u00e9 \u00e9nerg\u00e9tique, haute densit\u00e9 \u00e9nerg\u00e9tique, de leurs faibles pertes de chaleur et de leur utilisation potentielle pour le stockage de l&#039;\u00e9nergie solaire pendant les p\u00e9riodes saisonni\u00e8res. Les syst\u00e8mes \u00e0 absorption, en particulier, semblent \u00eatre une bonne alternative \u00e0 la compression m\u00e9canique des syst\u00e8mes de r\u00e9frig\u00e9ration standards pour diff\u00e9rentes raisons. Le fonctionnement de ces machines thermodynamiques est bas\u00e9 sur la mise en oeuvre de diff\u00e9rents \u00e9changeurs de chaleur et de masse (absorbeur, d\u00e9sorbeur, \u00e9vaporateur et condenseur). L&#039;objectif de ce projet de recherche est de caract\u00e9riser en d\u00e9tail les ph\u00e9nom\u00e8nes de transferts coupl\u00e9s de masse et de chaleur, non seulement \u00e0 l&#039;\u00e9chelle locale mais aussi \u00e0 l\u2019\u00e9chelle du composant, l\u2019\u00e9changeur le plus critique et le moins connu des machines \u00e0 absorption \u00e0 savoir l&#039;absorbeur. L&#039;approche adopt\u00e9e est bas\u00e9e sur l&#039;analyse thermodynamique de ces \u00e9changeurs, selon les d\u00e9veloppements r\u00e9cents de la Thermodynamique des Processus Irr\u00e9versibles (TIP), dans le but d&#039;identifier les diff\u00e9rentes sources d&#039;irr\u00e9versibilit\u00e9s responsables d&#039;une d\u00e9gradation des performances globales du syst\u00e8me.Le chapitre I pr\u00e9sente un \u00e9tat de l&#039;art des mod\u00e8les de transferts coupl\u00e9s de chaleur et de masse et des applications de la thermodynamique des processus irr\u00e9versibles \u00e0 l\u2019absorbeur, afin de comprendre les principales hypoth\u00e8ses et les limites des diff\u00e9rents mod\u00e8les. Pour une meilleure compr\u00e9hension des sources d\u2019irr\u00e9versibilit\u00e9s dans les \u00e9changeurs simples, le chapitre II est consacr\u00e9 \u00e0 l&#039;\u00e9tude d&#039;un \u00e9vaporateur avant d\u2019introduire les ph\u00e9nom\u00e8nes plus complexes observ\u00e9s dans l\u2019absorbeur. Les bilans thermiques du fluide caloporteur et du film sont r\u00e9solus simultan\u00e9ment \u00e0 travers un mod\u00e8le 2D utilisant un sch\u00e9ma implicite de diff\u00e9rences finies. Des analyses locale et globale ont \u00e9t\u00e9 r\u00e9alis\u00e9es afin d&#039;\u00e9tudier l&#039;impact de param\u00e8tres tels que les nombres de Reynolds du fluide caloporteur et du film mais aussi la temp\u00e9rature du film en entr\u00e9e sur la cr\u00e9ation d&#039;entropie (irr\u00e9versibilit\u00e9s thermique et visqueuse) et sur les efficacit\u00e9s thermique et d&#039;\u00e9vaporation pour les configurations \u00e0 co et contre-courant. Le chapitre III d\u00e9veloppe un mod\u00e8le 2D d&#039;absorbeur. Afin d&#039;\u00e9tudier le cas r\u00e9el de l&#039;absorbeur, le fluide caloporteur est suppos\u00e9 s&#039;\u00e9couler \u00e0 contre-courant et diff\u00e9rents r\u00e9gimes d&#039;\u00e9coulement du fluide caloporteur sont \u00e9tudi\u00e9s et compar\u00e9s aux cas limites - parois adiabatique et isotherme. Une formulation locale de la cr\u00e9ation d&#039;entropie est propos\u00e9e pour identifier les diff\u00e9rentes sources d&#039;irr\u00e9versibilit\u00e9s dans le but de les localiser et de les quantifier. Le chapitre IV permet une analyse globale du comportement des diff\u00e9rentes sources de cr\u00e9ation d&#039;entropie en consid\u00e9rant diff\u00e9rentes conditions de fonctionnement. Le facteur d&#039;\u00e9quilibre est introduit pour \u00e9tudier l&#039;impact des d\u00e9bits du fluide caloporteur et du film sur le d\u00e9bit massique absorb\u00e9, le flux transf\u00e9r\u00e9 et la cr\u00e9ation d&#039;entropie. Une optimisation multi-objectifs est \u00e9galement r\u00e9alis\u00e9e. Deux approches d&#039;optimisation ont \u00e9t\u00e9 utilis\u00e9es afin de d\u00e9terminer le front de Pareto et de valider les solutions optimales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-19T09:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T16:11:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/offre-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l&#8217;am\u00e9lioration de l&#8217;efficacit\u00e9 des machines \u00e0 absorption\",\"datePublished\":\"2024-08-19T09:00:41+00:00\",\"dateModified\":\"2025-10-27T16:11:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/\"},\"wordCount\":1637,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/offre-3.jpg\",\"keywords\":[\"Absorber\",\"Absorbeur\",\"Absorption machines\",\"Analyses locale et globale\",\"Cr\u00e9ation d'entropie\",\"Entropy generation\",\"Evaporateur\",\"Evaporator\",\"Falling film\",\"Film tombant\",\"Local and overall analysis\",\"Machines \u00e0 absorption\"],\"articleSection\":[\"Documents\",\"M\u00e9moires de th\u00e8ses\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/\",\"name\":\"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l'am\u00e9lioration de l'efficacit\u00e9 des machines \u00e0 absorption - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/offre-3.jpg\",\"datePublished\":\"2024-08-19T09:00:41+00:00\",\"dateModified\":\"2025-10-27T16:11:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/offre-3.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/offre-3.jpg\",\"width\":424,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l&#8217;am\u00e9lioration de l&#8217;efficacit\u00e9 des machines \u00e0 absorption\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l'am\u00e9lioration de l'efficacit\u00e9 des machines \u00e0 absorption - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/","og_locale":"en_US","og_type":"article","og_title":"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l'am\u00e9lioration de l'efficacit\u00e9 des machines \u00e0 absorption","og_description":"R\u00e9sum\u00e9 : L'augmentation de la demande d'\u00e9nergie est principalement due \u00e0 l'augmentation de la consommation d'\u00e9nergie dans les secteurs du b\u00e2timent et du tertiaire o\u00f9 20% de la consommation d'\u00e9nergie est consacr\u00e9e \u00e0 la climatisation en raison de l'augmentation de la temp\u00e9rature moyenne mondiale de 1\u00b0C. Or, l'utilisation des appareils de chauffage et de climatisation conventionnels a un impact consid\u00e9rable sur l'environnement car ils contribuent au r\u00e9chauffement climatique. Agir dans le secteur du b\u00e2timent en produisant du froid et de la chaleur bas carbone permettrait de r\u00e9duire consid\u00e9rablement son impact environnemental.Ces derni\u00e8res ann\u00e9es, les syst\u00e8mes \u00e0 sorption ont suscit\u00e9 l'int\u00e9r\u00eat de la communaut\u00e9 scientifique en raison de leur bonne efficacit\u00e9 \u00e9nerg\u00e9tique, haute densit\u00e9 \u00e9nerg\u00e9tique, de leurs faibles pertes de chaleur et de leur utilisation potentielle pour le stockage de l'\u00e9nergie solaire pendant les p\u00e9riodes saisonni\u00e8res. Les syst\u00e8mes \u00e0 absorption, en particulier, semblent \u00eatre une bonne alternative \u00e0 la compression m\u00e9canique des syst\u00e8mes de r\u00e9frig\u00e9ration standards pour diff\u00e9rentes raisons. Le fonctionnement de ces machines thermodynamiques est bas\u00e9 sur la mise en oeuvre de diff\u00e9rents \u00e9changeurs de chaleur et de masse (absorbeur, d\u00e9sorbeur, \u00e9vaporateur et condenseur). L'objectif de ce projet de recherche est de caract\u00e9riser en d\u00e9tail les ph\u00e9nom\u00e8nes de transferts coupl\u00e9s de masse et de chaleur, non seulement \u00e0 l'\u00e9chelle locale mais aussi \u00e0 l\u2019\u00e9chelle du composant, l\u2019\u00e9changeur le plus critique et le moins connu des machines \u00e0 absorption \u00e0 savoir l'absorbeur. L'approche adopt\u00e9e est bas\u00e9e sur l'analyse thermodynamique de ces \u00e9changeurs, selon les d\u00e9veloppements r\u00e9cents de la Thermodynamique des Processus Irr\u00e9versibles (TIP), dans le but d'identifier les diff\u00e9rentes sources d'irr\u00e9versibilit\u00e9s responsables d'une d\u00e9gradation des performances globales du syst\u00e8me.Le chapitre I pr\u00e9sente un \u00e9tat de l'art des mod\u00e8les de transferts coupl\u00e9s de chaleur et de masse et des applications de la thermodynamique des processus irr\u00e9versibles \u00e0 l\u2019absorbeur, afin de comprendre les principales hypoth\u00e8ses et les limites des diff\u00e9rents mod\u00e8les. Pour une meilleure compr\u00e9hension des sources d\u2019irr\u00e9versibilit\u00e9s dans les \u00e9changeurs simples, le chapitre II est consacr\u00e9 \u00e0 l'\u00e9tude d'un \u00e9vaporateur avant d\u2019introduire les ph\u00e9nom\u00e8nes plus complexes observ\u00e9s dans l\u2019absorbeur. Les bilans thermiques du fluide caloporteur et du film sont r\u00e9solus simultan\u00e9ment \u00e0 travers un mod\u00e8le 2D utilisant un sch\u00e9ma implicite de diff\u00e9rences finies. Des analyses locale et globale ont \u00e9t\u00e9 r\u00e9alis\u00e9es afin d'\u00e9tudier l'impact de param\u00e8tres tels que les nombres de Reynolds du fluide caloporteur et du film mais aussi la temp\u00e9rature du film en entr\u00e9e sur la cr\u00e9ation d'entropie (irr\u00e9versibilit\u00e9s thermique et visqueuse) et sur les efficacit\u00e9s thermique et d'\u00e9vaporation pour les configurations \u00e0 co et contre-courant. Le chapitre III d\u00e9veloppe un mod\u00e8le 2D d'absorbeur. Afin d'\u00e9tudier le cas r\u00e9el de l'absorbeur, le fluide caloporteur est suppos\u00e9 s'\u00e9couler \u00e0 contre-courant et diff\u00e9rents r\u00e9gimes d'\u00e9coulement du fluide caloporteur sont \u00e9tudi\u00e9s et compar\u00e9s aux cas limites - parois adiabatique et isotherme. Une formulation locale de la cr\u00e9ation d'entropie est propos\u00e9e pour identifier les diff\u00e9rentes sources d'irr\u00e9versibilit\u00e9s dans le but de les localiser et de les quantifier. Le chapitre IV permet une analyse globale du comportement des diff\u00e9rentes sources de cr\u00e9ation d'entropie en consid\u00e9rant diff\u00e9rentes conditions de fonctionnement. Le facteur d'\u00e9quilibre est introduit pour \u00e9tudier l'impact des d\u00e9bits du fluide caloporteur et du film sur le d\u00e9bit massique absorb\u00e9, le flux transf\u00e9r\u00e9 et la cr\u00e9ation d'entropie. Une optimisation multi-objectifs est \u00e9galement r\u00e9alis\u00e9e. Deux approches d'optimisation ont \u00e9t\u00e9 utilis\u00e9es afin de d\u00e9terminer le front de Pareto et de valider les solutions optimales.","og_url":"https:\/\/greth.fr\/en\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2024-08-19T09:00:41+00:00","article_modified_time":"2025-10-27T16:11:21+00:00","og_image":[{"width":424,"height":283,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/offre-3.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l&#8217;am\u00e9lioration de l&#8217;efficacit\u00e9 des machines \u00e0 absorption","datePublished":"2024-08-19T09:00:41+00:00","dateModified":"2025-10-27T16:11:21+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/"},"wordCount":1637,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/offre-3.jpg","keywords":["Absorber","Absorbeur","Absorption machines","Analyses locale et globale","Cr\u00e9ation d'entropie","Entropy generation","Evaporateur","Evaporator","Falling film","Film tombant","Local and overall analysis","Machines \u00e0 absorption"],"articleSection":["Documents","M\u00e9moires de th\u00e8ses"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/","url":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/","name":"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l'am\u00e9lioration de l'efficacit\u00e9 des machines \u00e0 absorption - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/offre-3.jpg","datePublished":"2024-08-19T09:00:41+00:00","dateModified":"2025-10-27T16:11:21+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/offre-3.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/offre-3.jpg","width":424,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/analyse-thermodynamique-des-absorbeurs-a-film-tombant-pour-lamelioration-de-lefficacite-des-machines-a-absorption\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"Analyse thermodynamique des absorbeurs \u00e0 film tombant pour l&#8217;am\u00e9lioration de l&#8217;efficacit\u00e9 des machines \u00e0 absorption"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/21053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=21053"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/21053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/100"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=21053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=21053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=21053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}