{"id":14703,"date":"2021-10-14T16:30:37","date_gmt":"2021-10-14T14:30:37","guid":{"rendered":"https:\/\/greth.fr\/?p=14703"},"modified":"2023-03-02T15:57:21","modified_gmt":"2023-03-02T14:57:21","slug":"etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/","title":{"rendered":"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons"},"content":{"rendered":"<p><strong><span style=\"text-decoration: underline;\">Summary :<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Ce travail de th\u00e8se porte sur l\u2019utilisation des ultrasons comme m\u00e9thode d\u2019intensification des transferts thermiques en convection forc\u00e9e. L\u2019objectif de ce travail de th\u00e8se vise \u00e0 mieux comprendre les m\u00e9canismes physiques en place, permettant ainsi d\u2019optimiser les param\u00e8tres op\u00e9ratoires dans une perspective d\u2019utilisation industrielle. Pour cela, une section d\u2019essais, constitu\u00e9e d\u2019un canal d\u2019\u00e9coulement et d\u2019une plaque chauffante, a \u00e9t\u00e9 utilis\u00e9e. Cette section d\u2019essais permet d\u2019int\u00e9grer un ou deux \u00e9metteurs ultrasonores. L\u2019\u00e9tude de l\u2019influence des ultrasons est structur\u00e9e \u00e0 partir d\u2019une analyse du transfert thermique convectif et de l\u2019hydrodynamique. De plus, l\u2019ensemble de cette \u00e9tude est r\u00e9alis\u00e9 pour deux fr\u00e9quences ultrasonores distinctes, 25 kHz et 2 MHz. Dans un premier temps, les effets produits par la combinaison de plusieurs champs ultrasonores de fr\u00e9quence diff\u00e9rente ont \u00e9t\u00e9 \u00e9tudi\u00e9. Les r\u00e9sultats ont montr\u00e9 que la combinaison de champs ultrasonores permet d\u2019am\u00e9liorer l\u2019activit\u00e9 cavitationnelle, se traduisant par une g\u00e9n\u00e9ration de turbulence au sein de l\u2019\u00e9coulement. Lorsque cette turbulence est g\u00e9n\u00e9r\u00e9e \u00e0 proximit\u00e9 de la paroi chauffante, l\u2019intensification du transfert thermique produite par les ultrasons est plus importante que dans le cas d\u2019un champ ultrasonore unique. Dans un second temps, l\u2019\u00e9tude se porte sur l\u2019influence des ultrasons sur le transfert thermique en fonction du r\u00e9gime d\u2019\u00e9coulement. L\u2019augmentation du nombre de Reynolds se traduit par une att\u00e9nuation des effets hydrodynamiques produits par les ultrasons, n\u00e9anmoins les effets sur le transfert thermique diff\u00e8rent selon la fr\u00e9quence ultrasonore. L\u2019ensemble des r\u00e9sultats de cette \u00e9tude ont d\u00e9montr\u00e9 un lien \u00e9troit entre l\u2019intensification du transfert thermique produite par les ultrasons et l\u2019\u00e9paisseur initiale de la couche limite thermique en conditions silencieuses. Enfin, une analyse \u00e9nerg\u00e9tique a permis de montrer l\u2019int\u00e9r\u00eat de l\u2019utilisation des ultrasons pour intensifier les transferts thermiques dans le cadre d\u2019applications industrielles.<\/p>\n<table width=\"100%\" border=\"1\">\n<tr>\n<td><strong>Author<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Christophe PONCET<\/td>\n<\/tr>\n<tr>\n<td><strong>Date de publication<\/strong><\/td>\n<\/tr>\n<tr>\n<td>15 Juillet 2021<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Hydrodynamique, transfert de chaleur, intensification, ultrasons<\/td>\n<\/tr>\n<\/table>\n\n&nbsp;<br \/>\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 : Ce travail de th\u00e8se porte sur l\u2019utilisation des ultrasons comme m\u00e9thode d\u2019intensification des transferts thermiques en convection forc\u00e9e. L\u2019objectif de ce travail de th\u00e8se vise \u00e0 mieux comprendre les m\u00e9canismes physiques en place, permettant ainsi d\u2019optimiser les param\u00e8tres op\u00e9ratoires dans une perspective d\u2019utilisation industrielle. Pour cela, une section d\u2019essais, constitu\u00e9e d\u2019un canal d\u2019\u00e9coulement &hellip;<\/p>","protected":false},"author":1,"featured_media":962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[6484,6461,6378,6485],"class_list":["post-14703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memoires-theses","tag-hydrodynamique","tag-intensification","tag-transfert-de-chaleur","tag-ultrasons"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 : Ce travail de th\u00e8se porte sur l\u2019utilisation des ultrasons comme m\u00e9thode d\u2019intensification des transferts thermiques en convection forc\u00e9e. L\u2019objectif de ce travail de th\u00e8se vise \u00e0 mieux comprendre les m\u00e9canismes physiques en place, permettant ainsi d\u2019optimiser les param\u00e8tres op\u00e9ratoires dans une perspective d\u2019utilisation industrielle. Pour cela, une section d\u2019essais, constitu\u00e9e d\u2019un canal d\u2019\u00e9coulement &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T14:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T14:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"387\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons\",\"datePublished\":\"2021-10-14T14:30:37+00:00\",\"dateModified\":\"2023-03-02T14:57:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/\"},\"wordCount\":751,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"keywords\":[\"hydrodynamique\",\"intensification\",\"Transfert de chaleur\",\"ultrasons\"],\"articleSection\":[\"M\u00e9moires de th\u00e8ses\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/\",\"name\":\"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"datePublished\":\"2021-10-14T14:30:37+00:00\",\"dateModified\":\"2023-03-02T14:57:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"width\":387,\"height\":310},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/","og_locale":"en_US","og_type":"article","og_title":"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons","og_description":"R\u00e9sum\u00e9 : Ce travail de th\u00e8se porte sur l\u2019utilisation des ultrasons comme m\u00e9thode d\u2019intensification des transferts thermiques en convection forc\u00e9e. L\u2019objectif de ce travail de th\u00e8se vise \u00e0 mieux comprendre les m\u00e9canismes physiques en place, permettant ainsi d\u2019optimiser les param\u00e8tres op\u00e9ratoires dans une perspective d\u2019utilisation industrielle. Pour cela, une section d\u2019essais, constitu\u00e9e d\u2019un canal d\u2019\u00e9coulement &hellip;","og_url":"https:\/\/greth.fr\/en\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2021-10-14T14:30:37+00:00","article_modified_time":"2023-03-02T14:57:21+00:00","og_image":[{"width":387,"height":310,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons","datePublished":"2021-10-14T14:30:37+00:00","dateModified":"2023-03-02T14:57:21+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/"},"wordCount":751,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","keywords":["hydrodynamique","intensification","Transfert de chaleur","ultrasons"],"articleSection":["M\u00e9moires de th\u00e8ses"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/","url":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/","name":"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","datePublished":"2021-10-14T14:30:37+00:00","dateModified":"2023-03-02T14:57:21+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","width":387,"height":310},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/etude-de-linfluence-des-parametres-operatoires-sur-lintensification-du-transfert-de-chaleur-en-presence-dultrasons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"Etude de l\u2019influence des param\u00e8tres op\u00e9ratoires sur l\u2019intensification du transfert de chaleur en pr\u00e9sence d\u2019ultrasons"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/14703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=14703"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/14703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/962"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=14703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=14703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=14703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}