{"id":14068,"date":"2020-11-04T10:00:01","date_gmt":"2020-11-04T09:00:01","guid":{"rendered":"https:\/\/greth.fr\/?p=14068"},"modified":"2023-05-17T16:17:48","modified_gmt":"2023-05-17T14:17:48","slug":"logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/","title":{"rendered":"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>\u00c9tude comparative des r\u00e9sultats de calculs de performance d\u2019un \u00e9changeur entre les logiciels EchTherm, HTRI, et les r\u00e9sultats exp\u00e9rimentaux issus d'un banc d'essais \u2013 \u00c9changeur \u00e0 tubes et calandre<\/strong><\/span><\/p>\n<div id=\"footable_parent_18453\"\n         class=\"footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent semantic_ui\">\n                <table data-ninja_table_instance=\"ninja_table_instance_0\" data-footable_id=\"18453\" data-filter-delay=\"1000\" aria-label=\"Rapport 2020 - 1\"            id=\"footable_18453\"\n           data-unique_identifier=\"ninja_table_unique_id_940553937_18453\"\n           class=\"foo-table ninja_footable foo_table_18453 ninja_table_unique_id_940553937_18453 ui table  nt_type_ajax_table vertical_centered  footable-paging-right hide_all_borders ninjatable_hide_header_row ninja_table_search_disabled ninja_table_pro\">\n                <colgroup>\n                            <col class=\"ninja_column_0\">\n                            <col class=\"ninja_column_1\">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px; font-family: arial, helvetica, sans-serif;\">Le pr\u00e9sent rapport technique est organis\u00e9 de fa\u00e7on \u00e0 fournir avec le plus de clart\u00e9 possible l\u2019ensemble des \u00e9l\u00e9ments qui ont permis \u00e0 ce travail d\u2019\u00eatre men\u00e9 \u00e0 bien. Ainsi, voici les th\u00e8mes des principaux chapitres de ce rapport :<\/span><\/p>\n<ul>\n<li>Pr\u00e9sentation de l\u2019\u00e9changeur et du banc d\u2019essais ;<\/li>\n<li>Choix des points d\u2019essai ;<\/li>\n<li>Pr\u00e9sentation de la m\u00e9trologie ;<\/li>\n<li>Analyse des incertitudes de mesures ;<\/li>\n<li>Traitement et m\u00e9thode d\u2019analyse d\u2019un point d\u2019essai ;<\/li>\n<li>Analyse et comparaison des r\u00e9sultats sur chaque cas d\u2019\u00e9tude ;<\/li>\n<li>Analyse globale et explications associ\u00e9es.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">On note que les r\u00e9sultats des comparaisons (Logiciels VS Exp\u00e9rimentations) sont pr\u00e9sent\u00e9s sous la forme de tableaux complets mais \u00e9galement sous forme de graphiques de type Radar afin de proposer une analyse des r\u00e9sultats qui se veut visuelle, rapide et efficace tout en restant suffisamment quantitative.<\/p>\n<p style=\"text-align: justify;\">En toute fin de document, une synth\u00e8se sera fournie et permettra de proposer des perspectives sur les axes de d\u00e9veloppement et d\u2019am\u00e9lioration du logiciel EchTherm.<\/p>\n<p style=\"text-align: justify;\">Ce document est mis \u00e0 disposition de fa\u00e7on exclusive aux adh\u00e9rents du GRETh.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"\/en\/etude-comparative-des-resultats-de-calculs-de-performance-dun-echangeur-entre-les-logiciels-echtherm-htri-et-les-resultats-experimentaux-issus-dun-banc-dessais-echangeur-a-tub\/\"><strong><span style=\"font-size: 16px; font-family: arial, helvetica, sans-serif;\">CLICK HERE TO VIEW THE REPORT<\/span><\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c9tude comparative des r\u00e9sultats de calculs de performance d\u2019un \u00e9changeur entre les logiciels EchTherm, HTRI, et les r\u00e9sultats exp\u00e9rimentaux issus d&#8217;un banc d&#8217;essais \u2013 \u00c9changeur \u00e0 tubes et calandre Le pr\u00e9sent rapport technique est organis\u00e9 de fa\u00e7on \u00e0 fournir avec le plus de clart\u00e9 possible l\u2019ensemble des \u00e9l\u00e9ments qui ont permis \u00e0 ce travail d\u2019\u00eatre &hellip;<\/p>","protected":false},"author":1,"featured_media":14072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-14068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-du-greth"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh\" \/>\n<meta property=\"og:description\" content=\"\u00c9tude comparative des r\u00e9sultats de calculs de performance d\u2019un \u00e9changeur entre les logiciels EchTherm, HTRI, et les r\u00e9sultats exp\u00e9rimentaux issus d&#039;un banc d&#039;essais \u2013 \u00c9changeur \u00e0 tubes et calandre Le pr\u00e9sent rapport technique est organis\u00e9 de fa\u00e7on \u00e0 fournir avec le plus de clart\u00e9 possible l\u2019ensemble des \u00e9l\u00e9ments qui ont permis \u00e0 ce travail d\u2019\u00eatre &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T09:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T14:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2020\/11\/nr11-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh\",\"datePublished\":\"2020-11-04T09:00:01+00:00\",\"dateModified\":\"2023-05-17T14:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/\"},\"wordCount\":241,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/nr11-2020.jpg\",\"articleSection\":[\"Les actualit\u00e9s du GRETh\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/\",\"name\":\"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/nr11-2020.jpg\",\"datePublished\":\"2020-11-04T09:00:01+00:00\",\"dateModified\":\"2023-05-17T14:17:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/nr11-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/nr11-2020.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/","og_locale":"en_US","og_type":"article","og_title":"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh","og_description":"\u00c9tude comparative des r\u00e9sultats de calculs de performance d\u2019un \u00e9changeur entre les logiciels EchTherm, HTRI, et les r\u00e9sultats exp\u00e9rimentaux issus d'un banc d'essais \u2013 \u00c9changeur \u00e0 tubes et calandre Le pr\u00e9sent rapport technique est organis\u00e9 de fa\u00e7on \u00e0 fournir avec le plus de clart\u00e9 possible l\u2019ensemble des \u00e9l\u00e9ments qui ont permis \u00e0 ce travail d\u2019\u00eatre &hellip;","og_url":"https:\/\/greth.fr\/en\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2020-11-04T09:00:01+00:00","article_modified_time":"2023-05-17T14:17:48+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2020\/11\/nr11-2020.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh","datePublished":"2020-11-04T09:00:01+00:00","dateModified":"2023-05-17T14:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/"},"wordCount":241,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2020\/11\/nr11-2020.jpg","articleSection":["Les actualit\u00e9s du GRETh"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/","url":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/","name":"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2020\/11\/nr11-2020.jpg","datePublished":"2020-11-04T09:00:01+00:00","dateModified":"2023-05-17T14:17:48+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2020\/11\/nr11-2020.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2020\/11\/nr11-2020.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/logiciels-vs-experimentations-venez-consulter-le-nouveau-rapport-technique-du-greth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"LOGICIELS VS EXPERIMENTATIONS : Rapport technique du GRETh"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/14068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=14068"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/14068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/14072"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=14068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=14068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=14068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}