{"id":13257,"date":"2019-09-23T11:15:01","date_gmt":"2019-09-23T09:15:01","guid":{"rendered":"https:\/\/greth.fr\/?p=13257"},"modified":"2023-03-02T16:13:12","modified_gmt":"2023-03-02T15:13:12","slug":"optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/","title":{"rendered":"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur"},"content":{"rendered":"<p><strong><span style=\"text-decoration: underline;\">Summary :<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Les \u00e9changeurs de chaleur sont utilis\u00e9s dans de nombreux secteurs industriels. L'optimisation de leurs performances est donc de premi\u00e8re importance pour r\u00e9duire la consommation \u00e9nerg\u00e9tique. Le  comportement d'un \u00e9changeur est intrins\u00e8quement multi\u00e9chelle : l'\u00e9chelle locale de l'intensification des ph\u00e9nom\u00e8nes de transfert thermique c\u00f4toie une \u00e9chelle plus globale o\u00f9 interviennent des ph\u00e9nom\u00e8nes de distribution de d\u00e9bit. Un \u00e9changeur de chaleur est \u00e9galement le si\u00e8ge de diff\u00e9rents ph\u00e9nom\u00e8nes physiques, tels que la m\u00e9canique des fluides, la thermique et l'encrassement. Les pr\u00e9sents travaux proposent une m\u00e9thode d'optimisation multiobjectif de la forme des \u00e9changeurs, robuste, pouvant traiter les aspects multi\u00e9chelles et multiphysiques et applicable dans un contexte industriel. Les performances de l'\u00e9changeur sont \u00e9valu\u00e9es par des simulations de m\u00e9canique des fluides num\u00e9rique (CFD) et par des m\u00e9thodes globales (\u0454-NUT). Suite \u00e0 une \u00e9tude bibliographique, une m\u00e9thode de m\u00e9tamod\u00e9lisation par krigeage associ\u00e9e \u00e0 un algorithme g\u00e9n\u00e9tique ont \u00e9t\u00e9 retenus. Des m\u00e9thodes de visualisation adapt\u00e9es (clustering et Self-Organizing Maps) sont utilis\u00e9es pour analyser les r\u00e9sultats. Le m\u00e9tamod\u00e8le permet d'approcher la r\u00e9ponse d'un simulateur (CFD) et d'en fournir une pr\u00e9diction dont l'interrogation est peu on\u00e9reuse. Le krigeage permet de prendre en compte une discontinuit\u00e9 et des perturbations de la r\u00e9ponse du simulateur par l'ajout d'un effet de p\u00e9pite. Il permet \u00e9galement l'utilisation de strat\u00e9gies d'enrichissement construisant des approximations pr\u00e9cises \u00e0 moindre co\u00fbt. Cette m\u00e9thode est appliqu\u00e9e \u00e0 diff\u00e9rentes configurations repr\u00e9sentatives du comportement de l'\u00e9changeur, permettant de s'assurer de sa robustesse lorsque le simulateur change, lorsque l'aspect multi\u00e9chelle est pris en compte ou lorsque une physique d'encrassement est consid\u00e9r\u00e9e. Il a \u00e9t\u00e9 \u00e9tabli que l'\u00e9tape de m\u00e9tamod\u00e9lisation assure la robustesse de la m\u00e9thode et l'int\u00e9gration de l'aspect multi\u00e9chelle. Elle permet aussi de construire des corr\u00e9lations \u00e0 l'\u00e9chelle locale qui sont ensuite utilis\u00e9es pour d\u00e9terminer les performances globales de l'\u00e9changeur. Dans un contexte industriel, les m\u00e9thodes d'analyse permettent de mettre en \u00e9vidence un nombre fini de formes r\u00e9alisant un compromis des fonctions objectif antagonistes. <\/p>\n<table width=\"100%\" border=\"1\">\n<tr>\n<td><strong>Author<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Franck MASTRIPPOLITO<\/td>\n<\/tr>\n<tr>\n<td><strong>Date de publication<\/strong><\/td>\n<\/tr>\n<tr>\n<td>14 D\u00e9cembre 2018<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>\u00c9changeur de chaleur, m\u00e9canique des fluides num\u00e9rique - CFD, optimisation multiobjectif, krigeage, strat\u00e9gie d'enrichissement, Self-Organizing Maps<\/td>\n<\/tr>\n<\/table>\n\n&nbsp;<br \/>\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 : Les \u00e9changeurs de chaleur sont utilis\u00e9s dans de nombreux secteurs industriels. L&#8217;optimisation de leurs performances est donc de premi\u00e8re importance pour r\u00e9duire la consommation \u00e9nerg\u00e9tique. Le comportement d&#8217;un \u00e9changeur est intrins\u00e8quement multi\u00e9chelle : l&#8217;\u00e9chelle locale de l&#8217;intensification des ph\u00e9nom\u00e8nes de transfert thermique c\u00f4toie une \u00e9chelle plus globale o\u00f9 interviennent des ph\u00e9nom\u00e8nes de distribution &hellip;<\/p>","protected":false},"author":1,"featured_media":963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,21],"tags":[6552,6403,6569,6567,6568,6571,6570],"class_list":["post-13257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents","category-memoires-theses","tag-cfd","tag-echangeur-de-chaleur","tag-krigeage","tag-mecanique-des-fluides-numerique","tag-optimisation-multiobjectif","tag-self-organizing-maps","tag-strategie-denrichissement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 : Les \u00e9changeurs de chaleur sont utilis\u00e9s dans de nombreux secteurs industriels. L&#039;optimisation de leurs performances est donc de premi\u00e8re importance pour r\u00e9duire la consommation \u00e9nerg\u00e9tique. Le comportement d&#039;un \u00e9changeur est intrins\u00e8quement multi\u00e9chelle : l&#039;\u00e9chelle locale de l&#039;intensification des ph\u00e9nom\u00e8nes de transfert thermique c\u00f4toie une \u00e9chelle plus globale o\u00f9 interviennent des ph\u00e9nom\u00e8nes de distribution &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-23T09:15:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T15:13:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur\",\"datePublished\":\"2019-09-23T09:15:01+00:00\",\"dateModified\":\"2023-03-02T15:13:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/\"},\"wordCount\":815,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-7.jpg\",\"keywords\":[\"CFD\",\"\u00e9changeur de chaleur\",\"krigeage\",\"m\u00e9canique des fluides num\u00e9rique\",\"optimisation multiobjectif\",\"self-organizing maps\",\"strat\u00e9gie d'enrichissement\"],\"articleSection\":[\"Documents\",\"M\u00e9moires de th\u00e8ses\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/\",\"name\":\"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-7.jpg\",\"datePublished\":\"2019-09-23T09:15:01+00:00\",\"dateModified\":\"2023-03-02T15:13:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-7.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-7.jpg\",\"width\":435,\"height\":276},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/","og_locale":"en_US","og_type":"article","og_title":"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur","og_description":"R\u00e9sum\u00e9 : Les \u00e9changeurs de chaleur sont utilis\u00e9s dans de nombreux secteurs industriels. L'optimisation de leurs performances est donc de premi\u00e8re importance pour r\u00e9duire la consommation \u00e9nerg\u00e9tique. Le comportement d'un \u00e9changeur est intrins\u00e8quement multi\u00e9chelle : l'\u00e9chelle locale de l'intensification des ph\u00e9nom\u00e8nes de transfert thermique c\u00f4toie une \u00e9chelle plus globale o\u00f9 interviennent des ph\u00e9nom\u00e8nes de distribution &hellip;","og_url":"https:\/\/greth.fr\/en\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2019-09-23T09:15:01+00:00","article_modified_time":"2023-03-02T15:13:12+00:00","og_image":[{"width":435,"height":276,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-7.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur","datePublished":"2019-09-23T09:15:01+00:00","dateModified":"2023-03-02T15:13:12+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/"},"wordCount":815,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-7.jpg","keywords":["CFD","\u00e9changeur de chaleur","krigeage","m\u00e9canique des fluides num\u00e9rique","optimisation multiobjectif","self-organizing maps","strat\u00e9gie d'enrichissement"],"articleSection":["Documents","M\u00e9moires de th\u00e8ses"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/","url":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/","name":"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-7.jpg","datePublished":"2019-09-23T09:15:01+00:00","dateModified":"2023-03-02T15:13:12+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-7.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-7.jpg","width":435,"height":276},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/optimisation-de-forme-numerique-de-problemes-multiphysiques-et-multiechelles-application-aux-echangeurs-de-chaleur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"Optimisation de forme num\u00e9rique de probl\u00e8mes multiphysiques et multi\u00e9chelles : Application aux \u00e9changeurs de chaleur"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/13257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=13257"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/13257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/963"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=13257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=13257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=13257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}