{"id":1197,"date":"2013-04-19T12:10:08","date_gmt":"2013-04-19T10:10:08","guid":{"rendered":"http:\/\/greth.fr\/?p=1197"},"modified":"2023-02-23T17:14:12","modified_gmt":"2023-02-23T16:14:12","slug":"etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/","title":{"rendered":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant"},"content":{"rendered":"<p><strong><span style=\"text-decoration: underline;\">Summary :<\/span><\/strong><br \/>\nLes pompes \u00e0 chaleur thermo\u00e9lectriques (PACTE) pr\u00e9sentent diff\u00e9rents avantages par rapport aux pompes \u00e0 chaleur thermodynamiques classiques. Plus particuli\u00e8rement, les performances des PACTE sont int\u00e9ressantes lorsque les \u00e9carts de temp\u00e9rature entre sources sont modestes, ce qui est par exemple le cas du chauffage a\u00e9raulique des b\u00e2timents basse consommation (BBC) \u00e0 partir d'une Ventilation M\u00e9canique Double Flux (VMC DF). L'objectif de l'\u00e9tude est donc de d\u00e9velopper un d\u00e9monstrateur de pompe \u00e0 chaleur thermo\u00e9lectrique r\u00e9versible capable d'assurer la puissance de chauffage\/refroidissement n\u00e9cessaire \u00e0 un logement de type BBC. Ce travail repose sur diff\u00e9rents mod\u00e8les analytiques et num\u00e9riques valid\u00e9s exp\u00e9rimentalement. Cette \u00e9tude vise \u00e0 concevoir un syst\u00e8me de pompe \u00e0 chaleur thermo\u00e9lectrique performant, l'objectif \u00e9tant l'am\u00e9lioration du coefficient de performance (COP) de la PACTE. Les transferts de chaleur \u00e0 la surface des \u00e9l\u00e9ments thermo\u00e9lectriques sont intensifi\u00e9s par la technique du jet impactant, et le dimensionnement du syst\u00e8me est optimis\u00e9 en fonction des conditions d'utilisation. Avec le d\u00e9monstrateur de r\u00e9sultats pr\u00e9c\u00e9dents de la PACTE, le COP saisonnier a \u00e9t\u00e9 d\u00e9termin\u00e9. Apr\u00e8s couplage au b\u00e2timent, cela a permis de montrer une nette am\u00e9lioration des performances du syst\u00e8me.<\/p>\n<table width=\"100%\" border=\"1\">\n<tr>\n<td><strong>Auteur(s)<\/strong><\/td>\n<\/tr>\n<tr>\n<td>KIM Yeweon<\/td>\n<\/tr>\n<tr>\n<td><strong>Ann\u00e9e<\/strong><\/td>\n<\/tr>\n<tr>\n<td>2013<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Pompe \u00e0 chaleur thermo\u00e9lectrique, Jet impactant, Pompes \u00e0 chaleur<\/td>\n<\/tr>\n<\/table>\n\n&nbsp;<br \/>\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 : Les pompes \u00e0 chaleur thermo\u00e9lectriques (PACTE) pr\u00e9sentent diff\u00e9rents avantages par rapport aux pompes \u00e0 chaleur thermodynamiques classiques. Plus particuli\u00e8rement, les performances des PACTE sont int\u00e9ressantes lorsque les \u00e9carts de temp\u00e9rature entre sources sont modestes, ce qui est par exemple le cas du chauffage a\u00e9raulique des b\u00e2timents basse consommation (BBC) \u00e0 partir d&#8217;une Ventilation &hellip;<\/p>","protected":false},"author":1,"featured_media":962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,21],"tags":[],"class_list":["post-1197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents","category-memoires-theses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 : Les pompes \u00e0 chaleur thermo\u00e9lectriques (PACTE) pr\u00e9sentent diff\u00e9rents avantages par rapport aux pompes \u00e0 chaleur thermodynamiques classiques. Plus particuli\u00e8rement, les performances des PACTE sont int\u00e9ressantes lorsque les \u00e9carts de temp\u00e9rature entre sources sont modestes, ce qui est par exemple le cas du chauffage a\u00e9raulique des b\u00e2timents basse consommation (BBC) \u00e0 partir d&#039;une Ventilation &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-19T10:10:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-23T16:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"387\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant\",\"datePublished\":\"2013-04-19T10:10:08+00:00\",\"dateModified\":\"2023-02-23T16:14:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/\"},\"wordCount\":637,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"articleSection\":[\"Documents\",\"M\u00e9moires de th\u00e8ses\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/\",\"name\":\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"datePublished\":\"2013-04-19T10:10:08+00:00\",\"dateModified\":\"2023-02-23T16:14:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-6.jpg\",\"width\":387,\"height\":310},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/","og_locale":"en_US","og_type":"article","og_title":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant","og_description":"R\u00e9sum\u00e9 : Les pompes \u00e0 chaleur thermo\u00e9lectriques (PACTE) pr\u00e9sentent diff\u00e9rents avantages par rapport aux pompes \u00e0 chaleur thermodynamiques classiques. Plus particuli\u00e8rement, les performances des PACTE sont int\u00e9ressantes lorsque les \u00e9carts de temp\u00e9rature entre sources sont modestes, ce qui est par exemple le cas du chauffage a\u00e9raulique des b\u00e2timents basse consommation (BBC) \u00e0 partir d'une Ventilation &hellip;","og_url":"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2013-04-19T10:10:08+00:00","article_modified_time":"2023-02-23T16:14:12+00:00","og_image":[{"width":387,"height":310,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant","datePublished":"2013-04-19T10:10:08+00:00","dateModified":"2023-02-23T16:14:12+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/"},"wordCount":637,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","articleSection":["Documents","M\u00e9moires de th\u00e8ses"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/","url":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/","name":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","datePublished":"2013-04-19T10:10:08+00:00","dateModified":"2023-02-23T16:14:12+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-6.jpg","width":387,"height":310},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-dune-pompe-a-chaleur-thermoelectrique-innovante-basee-sur-une-conception-integree-et-la-technique-du-jet-impactant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d\u2019une pompe \u00e0 chaleur thermo\u00e9lectrique innovante bas\u00e9e sur une conception int\u00e9gr\u00e9e et la technique du jet impactant"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/1197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=1197"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/1197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/962"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=1197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=1197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=1197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}