{"id":1068,"date":"1999-11-26T10:00:44","date_gmt":"1999-11-26T09:00:44","guid":{"rendered":"http:\/\/greth.fr\/?p=1068"},"modified":"2023-02-24T14:37:36","modified_gmt":"2023-02-24T13:37:36","slug":"modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/","title":{"rendered":"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale"},"content":{"rendered":"<p><strong><span style=\"text-decoration: underline;\">Summary :<\/span><\/strong><br \/>\nCe travail porte sur le dimensionnement thermique des bouilleurs \u00e0 tubes horizontaux avec \u00e9vaporation extra-tubulaire \u00e9quip\u00e9s de tubes lisses. Le probl\u00e8me consiste essentiellement \u00e0 pr\u00e9dire le coefficient d\u2019\u00e9change thermique entre le fluide en \u00e9vaporation et la paroi ext\u00e9rieure des tubes, et se pose \u00e0 diff\u00e9rentes \u00e9chelles indissociables : \u00e0 l\u2019\u00e9chelle d\u2019un tube, le coefficient d\u2019\u00e9change est fortement d\u00e9pendant des conditions hydrodynamiques locales, qui sont d\u00e9termin\u00e9es par l\u2019\u00e9coulement diphasique s\u2019\u00e9tablissant \u00e0 l\u2019\u00e9chelle du bouilleur. Or cet \u00e9coulement est gouvern\u00e9 essentiellement par une convection naturelle li\u00e9e \u00e0 la production de vapeur, qui d\u00e9pend \u00e0 son tour du coefficient d\u2019\u00e9change au niveau des tubes. Les m\u00e9thodes utilis\u00e9es actuellement pour le dimensionnement thermique de ces bouilleurs pr\u00e9sentent une grande incertitude, aussi bien en ce qui concerne les corr\u00e9lations d\u2019\u00e9valuation du coefficient d\u2019\u00e9change au niveau d\u2019un tube, que pour la mod\u00e9lisation de l\u2019\u00e9coulement diphasique \u00e0 l'\u00e9chelle du bouilleur.<\/p>\n<p>L\u2019objectif du pr\u00e9sent travail est de contribuer \u00e0 l\u2019am\u00e9lioration de ces m\u00e9thodes de dimensionnement. Il comprend une \u00e9tude exp\u00e9rimentale sous des conditions repr\u00e9sentatives des principales applications de ces appareils : un hydrocarbure (du n-pentane) circulant \u00e0 faible flux massique. Cette \u00e9tude a permis d\u2019analyser la structure de l\u2019\u00e9coulement local par des mesures du taux de vide, et de d\u00e9velopper sur cette base des corr\u00e9lations de pr\u00e9diction du taux de vide, de la perte de pression par frottement et du coefficient d\u2019\u00e9change thermique. L\u2019approche adopt\u00e9e est originale, du fait que les corr\u00e9lations propos\u00e9es utilisent la vitesse du liquide \u00e0 l\u2019aire de passage minimale entre les tubes comme variable caract\u00e9risant les effets hydrodynamiques sur la perte de pression par frottement et le coefficient d'\u00e9change ; les corr\u00e9lations se montrent nettement mieux adapt\u00e9es que celles propos\u00e9es dans la litt\u00e9rature, qui sont une transposition empirique des m\u00e9thodes utilis\u00e9es pour les \u00e9coulements \u00e0 l\u2019int\u00e9rieur d\u2019un tube. Par ailleurs, une nouvelle application du code de calcul MC3D a \u00e9t\u00e9 d\u00e9velopp\u00e9e dans le cadre de ce travail, int\u00e9grant les corr\u00e9lations d\u00e9velopp\u00e9es dans l'\u00e9tude exp\u00e9rimentale et permettant de mod\u00e9liser l\u2019\u00e9coulement diphasique au niveau du bouilleur, ce qui repr\u00e9sente un progr\u00e8s important par rapport aux m\u00e9thodes simplifi\u00e9es utilis\u00e9es dans la pratique.<\/p>\n<table width=\"100%\" border=\"1\">\n<tr>\n<td><strong>Auteur(s)<\/strong><\/td>\n<\/tr>\n<tr>\n<td>ROSER Roberto<\/td>\n<\/tr>\n<tr>\n<td><strong>Ann\u00e9e<\/strong><\/td>\n<\/tr>\n<tr>\n<td>1999<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Mod\u00e9lisation, bouilleurs \u00e0 tubes horizontaux<\/td>\n<\/tr>\n<\/table>\n\n&nbsp;<br \/>\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 : Ce travail porte sur le dimensionnement thermique des bouilleurs \u00e0 tubes horizontaux avec \u00e9vaporation extra-tubulaire \u00e9quip\u00e9s de tubes lisses. Le probl\u00e8me consiste essentiellement \u00e0 pr\u00e9dire le coefficient d\u2019\u00e9change thermique entre le fluide en \u00e9vaporation et la paroi ext\u00e9rieure des tubes, et se pose \u00e0 diff\u00e9rentes \u00e9chelles indissociables : \u00e0 l\u2019\u00e9chelle d\u2019un tube, le &hellip;<\/p>","protected":false},"author":1,"featured_media":173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,21],"tags":[],"class_list":["post-1068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents","category-memoires-theses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 : Ce travail porte sur le dimensionnement thermique des bouilleurs \u00e0 tubes horizontaux avec \u00e9vaporation extra-tubulaire \u00e9quip\u00e9s de tubes lisses. Le probl\u00e8me consiste essentiellement \u00e0 pr\u00e9dire le coefficient d\u2019\u00e9change thermique entre le fluide en \u00e9vaporation et la paroi ext\u00e9rieure des tubes, et se pose \u00e0 diff\u00e9rentes \u00e9chelles indissociables : \u00e0 l\u2019\u00e9chelle d\u2019un tube, le &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"1999-11-26T09:00:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-24T13:37:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/theses-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale\",\"datePublished\":\"1999-11-26T09:00:44+00:00\",\"dateModified\":\"2023-02-24T13:37:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/\"},\"wordCount\":807,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/theses-2.png\",\"articleSection\":[\"Documents\",\"M\u00e9moires de th\u00e8ses\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/\",\"name\":\"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/theses-2.png\",\"datePublished\":\"1999-11-26T09:00:44+00:00\",\"dateModified\":\"2023-02-24T13:37:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/theses-2.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/theses-2.png\",\"width\":250,\"height\":165},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/","og_locale":"en_US","og_type":"article","og_title":"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale","og_description":"R\u00e9sum\u00e9 : Ce travail porte sur le dimensionnement thermique des bouilleurs \u00e0 tubes horizontaux avec \u00e9vaporation extra-tubulaire \u00e9quip\u00e9s de tubes lisses. Le probl\u00e8me consiste essentiellement \u00e0 pr\u00e9dire le coefficient d\u2019\u00e9change thermique entre le fluide en \u00e9vaporation et la paroi ext\u00e9rieure des tubes, et se pose \u00e0 diff\u00e9rentes \u00e9chelles indissociables : \u00e0 l\u2019\u00e9chelle d\u2019un tube, le &hellip;","og_url":"https:\/\/greth.fr\/en\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"1999-11-26T09:00:44+00:00","article_modified_time":"2023-02-24T13:37:36+00:00","og_image":[{"width":250,"height":165,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/theses-2.png","type":"image\/png"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale","datePublished":"1999-11-26T09:00:44+00:00","dateModified":"2023-02-24T13:37:36+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/"},"wordCount":807,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/theses-2.png","articleSection":["Documents","M\u00e9moires de th\u00e8ses"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/","url":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/","name":"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/theses-2.png","datePublished":"1999-11-26T09:00:44+00:00","dateModified":"2023-02-24T13:37:36+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/theses-2.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/06\/theses-2.png","width":250,"height":165},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/modelisation-thermique-de-bouilleurs-a-tubes-horizontaux-etude-numerique-et-validation-experimentale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"Mod\u00e9lisation thermique de bouilleurs \u00e0 tubes horizontaux. \u00c9tude num\u00e9rique et validation exp\u00e9rimentale"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/1068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=1068"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/1068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/173"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=1068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=1068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=1068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}