{"id":1058,"date":"1997-10-17T16:00:05","date_gmt":"1997-10-17T14:00:05","guid":{"rendered":"http:\/\/greth.fr\/?p=1058"},"modified":"2023-02-24T14:39:02","modified_gmt":"2023-02-24T13:39:02","slug":"etude-numerique-et-experimentale-delectrofiltres-industriels","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-delectrofiltres-industriels\/","title":{"rendered":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d&#8217;\u00e9lectrofiltres industriels"},"content":{"rendered":"<p><strong><span style=\"text-decoration: underline;\">Summary :<\/span><\/strong><br \/>\nL'objectif du pr\u00e9sent travail r\u00e9side dans l'\u00e9tude des m\u00e9canismes physiques qui r\u00e9gissent la pr\u00e9cipitation \u00e9lectrostatique par l'interm\u00e9diaire d'un banc d'essais exp\u00e9rimental et de campagnes de mesures sur un site industriel. Un mod\u00e8le num\u00e9rique original utilisant une approche de m\u00e9canique des fluides et a\u00e9rosols est propos\u00e9 et \u00e9prouv\u00e9 avec les points exp\u00e9rimentaux dans trois types de g\u00e9om\u00e9tries industrielles.<\/p>\n<p>Ce travail de recherche est int\u00e9gr\u00e9 dans le cadre des \u00e9tudes g\u00e9n\u00e9rales du GRETh en mati\u00e8re d'encrassement particulaire en phase gazeuse. Il fait suite \u00e0 de nombreux travaux sur l'encrassement des \u00e9changeurs de chaleur. De plus, cette \u00e9tude, inscrite dans le cadre au projet Europ\u00e9en Joule sur l'encrassement des chambres \u00e0 combustion et la filtration \u00e0 haute temp\u00e9rature, a \u00e9t\u00e9 men\u00e9e en collaboration \u00e9troite avec le Centre Technique des Industries A\u00e9rauliques et Thermiques (CETIAT). La forte implication du CETIAT dans le domaine de l'\u00e9puration de l'air a facilit\u00e9 l'obtention d'informations sur les g\u00e9om\u00e9tries et les r\u00e9gimes de fonctionnements industriels fr\u00e9quemment rencontr\u00e9s.<\/p>\n<table width=\"100%\" border=\"1\">\n<tr>\n<td><strong>Auteur(s)<\/strong><\/td>\n<\/tr>\n<tr>\n<td>TOCHON Patrice<\/td>\n<\/tr>\n<tr>\n<td><strong>Ann\u00e9e<\/strong><\/td>\n<\/tr>\n<tr>\n<td>1997<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Electrofiltres industriels, pr\u00e9cipitation \u00e9lectrostatique, m\u00e9canique des fluides<\/td>\n<\/tr>\n<\/table>\n\n&nbsp;<br \/>\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 : L&#8217;objectif du pr\u00e9sent travail r\u00e9side dans l&#8217;\u00e9tude des m\u00e9canismes physiques qui r\u00e9gissent la pr\u00e9cipitation \u00e9lectrostatique par l&#8217;interm\u00e9diaire d&#8217;un banc d&#8217;essais exp\u00e9rimental et de campagnes de mesures sur un site industriel. Un mod\u00e8le num\u00e9rique original utilisant une approche de m\u00e9canique des fluides et a\u00e9rosols est propos\u00e9 et \u00e9prouv\u00e9 avec les points exp\u00e9rimentaux dans trois &hellip;<\/p>","protected":false},"author":1,"featured_media":964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,21],"tags":[],"class_list":["post-1058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents","category-memoires-theses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9tude num\u00e9rique et exp\u00e9rimentale d&#039;\u00e9lectrofiltres industriels - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-delectrofiltres-industriels\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d&#039;\u00e9lectrofiltres industriels\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 : L&#039;objectif du pr\u00e9sent travail r\u00e9side dans l&#039;\u00e9tude des m\u00e9canismes physiques qui r\u00e9gissent la pr\u00e9cipitation \u00e9lectrostatique par l&#039;interm\u00e9diaire d&#039;un banc d&#039;essais exp\u00e9rimental et de campagnes de mesures sur un site industriel. Un mod\u00e8le num\u00e9rique original utilisant une approche de m\u00e9canique des fluides et a\u00e9rosols est propos\u00e9 et \u00e9prouv\u00e9 avec les points exp\u00e9rimentaux dans trois &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-delectrofiltres-industriels\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"1997-10-17T14:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-24T13:39:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d&#8217;\u00e9lectrofiltres industriels\",\"datePublished\":\"1997-10-17T14:00:05+00:00\",\"dateModified\":\"2023-02-24T13:39:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/\"},\"wordCount\":597,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-8.jpg\",\"articleSection\":[\"Documents\",\"M\u00e9moires de th\u00e8ses\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/\",\"name\":\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d'\u00e9lectrofiltres industriels - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-8.jpg\",\"datePublished\":\"1997-10-17T14:00:05+00:00\",\"dateModified\":\"2023-02-24T13:39:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-8.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/theses-8.jpg\",\"width\":424,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/etude-numerique-et-experimentale-delectrofiltres-industriels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9tude num\u00e9rique et exp\u00e9rimentale d&#8217;\u00e9lectrofiltres industriels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d'\u00e9lectrofiltres industriels - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-delectrofiltres-industriels\/","og_locale":"en_US","og_type":"article","og_title":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d'\u00e9lectrofiltres industriels","og_description":"R\u00e9sum\u00e9 : L'objectif du pr\u00e9sent travail r\u00e9side dans l'\u00e9tude des m\u00e9canismes physiques qui r\u00e9gissent la pr\u00e9cipitation \u00e9lectrostatique par l'interm\u00e9diaire d'un banc d'essais exp\u00e9rimental et de campagnes de mesures sur un site industriel. Un mod\u00e8le num\u00e9rique original utilisant une approche de m\u00e9canique des fluides et a\u00e9rosols est propos\u00e9 et \u00e9prouv\u00e9 avec les points exp\u00e9rimentaux dans trois &hellip;","og_url":"https:\/\/greth.fr\/en\/etude-numerique-et-experimentale-delectrofiltres-industriels\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"1997-10-17T14:00:05+00:00","article_modified_time":"2023-02-24T13:39:02+00:00","og_image":[{"width":424,"height":283,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-8.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d&#8217;\u00e9lectrofiltres industriels","datePublished":"1997-10-17T14:00:05+00:00","dateModified":"2023-02-24T13:39:02+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/"},"wordCount":597,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-8.jpg","articleSection":["Documents","M\u00e9moires de th\u00e8ses"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/","url":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/","name":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d'\u00e9lectrofiltres industriels - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-8.jpg","datePublished":"1997-10-17T14:00:05+00:00","dateModified":"2023-02-24T13:39:02+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-8.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2015\/08\/theses-8.jpg","width":424,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/etude-numerique-et-experimentale-delectrofiltres-industriels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9tude num\u00e9rique et exp\u00e9rimentale d&#8217;\u00e9lectrofiltres industriels"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=1058"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/1058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/964"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=1058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}