{"id":10335,"date":"2018-11-05T15:12:58","date_gmt":"2018-11-05T14:12:58","guid":{"rendered":"https:\/\/greth.fr\/?p=10335"},"modified":"2023-03-02T15:32:33","modified_gmt":"2023-03-02T14:32:33","slug":"echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances","status":"publish","type":"post","link":"https:\/\/greth.fr\/en\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/","title":{"rendered":"\u00c9changeurs de chaleur &#8211; M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances"},"content":{"rendered":"&nbsp;<br \/>\n<strong><span style=\"text-decoration: underline;\">Summary :<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Le pr\u00e9sent rapport technique est une \u00e9tude g\u00e9n\u00e9rale portant sur <strong>les m\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances dans le domaine des \u00e9changeurs de chaleur.<\/strong><\/strong><\/p>\n<p style=\"text-align: justify;\">L\u2019objectif de ce rapport est de pr\u00e9senter les diverses m\u00e9thodes et techniques de d\u00e9tection de d\u00e9faillances des \u00e9changeurs de chaleur. Ce document est \u00e0 mis \u00e0 disposition de fa\u00e7on exclusive aux adh\u00e9rents du GRETh qui ont formul\u00e9 la demande d\u2019un rapport sur les m\u00e9thodes et techniques de d\u00e9tection lors de l\u2019Assembl\u00e9e G\u00e9n\u00e9rale de 2017. La pr\u00e9sente version de ce document constitue la premi\u00e8re \u00e9tape de la r\u00e9daction d\u2019un guide complet qui, \u00e0 terme, constituera une aide pr\u00e9cieuse pour les adh\u00e9rents amen\u00e9s \u00e0 aborder les difficiles probl\u00e8mes de d\u00e9faillances.  Ce rapport constituera ainsi, dans sa version finale, un guide permettant aux adh\u00e9rents d\u2019identifier les solutions \u00e0 apporter \u00e0 ces probl\u00e8mes.<\/p>\n<p style=\"text-align: justify;\">Le rapport est construit en 5 parties d\u00e9crites succinctement ci-dessous :<\/p>\n<ul>\n<li>En partie I, nous donnerons les \u00e9l\u00e9ments m\u00e9thodologiques permettant de formaliser la probl\u00e9matique des d\u00e9faillances observ\u00e9es sur les \u00e9changeurs thermiques.<\/li>\n<li>En partie II, il conviendra de pr\u00e9ciser les sp\u00e9cificit\u00e9s techniques des sympt\u00f4mes de d\u00e9faillances ainsi que des causes de d\u00e9faillances en diff\u00e9renciant les d\u00e9faillances issues de d\u00e9faut de conception\/fabrication\/construction et celles issues de l\u2019exploitation ou des interventions de maintenance. Il conviendra de d\u00e9finir plus pr\u00e9cis\u00e9ment la chaine de causalit\u00e9 qui permet de relier, par une chaine de causes probables, les d\u00e9fauts aux sympt\u00f4mes de d\u00e9faillances.<\/li>\n<li>En partie III, nous pr\u00e9senterons la m\u00e9trologie \u00ab traditionnelle \u00bb mises en \u0153uvre sur les \u00e9quipements et installations courantes en vue notamment d\u2019identifier les pertes de performances (i.e. lorsque des \u00e9carts significatifs avec les performances attendues sont constat\u00e9s) des \u00e9changeurs de chaleur en cours d\u2019exploitation ou lors de la r\u00e9ception d\u2018une installation thermique ou \u00e9nerg\u00e9tique.<\/li>\n<li>En partie IV, seront pr\u00e9sent\u00e9es les m\u00e9trologies avanc\u00e9es \u2013 essentiellement non intrusives - susceptibles d\u2019\u00eatre mises en \u0153uvre pour permettre une identification des causes et m\u00e9canismes g\u00e9n\u00e9rant les d\u00e9faillances observ\u00e9es. Les techniques et m\u00e9thodes m\u00e9trologiques mises en avant sont les suivantes :<br \/>\n- d\u00e9tection de temps de s\u00e9jour et techniques de traceurs,<br \/>\n- d\u00e9tection de champ de temp\u00e9rature par cam\u00e9ra infrarouge,<br \/>\n- d\u00e9tection par m\u00e9thodes vibro-acoustiques,<br \/>\n- d\u00e9tection par sondes de mesures et dispositif de visualisation de param\u00e8tres diphasiques.<\/li>\n<li>En partie V, nous nous attacherons \u00e0 pr\u00e9senter des outils actuels d\u2019analyse avanc\u00e9e des donn\u00e9es permettant l\u2019identification et la pr\u00e9diction de d\u00e9faillances.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La pr\u00e9sente premi\u00e8re version de ce document int\u00e8gre les parties I et II. La version finale verra l\u2019enrichissement du rapport par les parties III \u00e0 V.<\/p>\n<table width=\"100%\" border=\"1\">\n<tr>\n<td><strong>Auteur(s)<\/strong><\/td>\n<\/tr>\n<tr>\n<td>GRETh<\/td>\n<\/tr>\n<tr>\n<td><strong>Ann\u00e9e<\/strong><\/td>\n<\/tr>\n<tr>\n<td>2018<\/td>\n<\/tr>\n<tr>\n<td><strong>Keywords<\/strong><\/td>\n<\/tr>\n<tr>\n<td>D\u00e9faillance, d\u00e9tection, sympt\u00f4me, \u00e9changeur thermique, arbres de causes, corrosion, fuite, by-pass, contact thermique.<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<br \/>\n\n<a class=\"fullscreen-mode\" href=\"https:\/\/greth.fr\/en\/themencode-pdf-viewer-sc\/?tnc_pvfw=ZmlsZT1odHRwczovL2dyZXRoLmZyL3B1YmxpYy9wdWJsaWNhdGlvbnMvMjAxOC8wMi8wMi5wZGYmc2V0dGluZ3M9MTExMTEwMTExMTExMTExMTEwMCZsYW5nPWZyLUZS#page=&#038;zoom=auto&#038;pagemode=\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/greth.fr\/wp-content\/uploads\/2023\/11\/fullscreen-doc-en.png\" width=\"297\" border=\"0\" class=\"aligncenter size-full\"><\/a><br><iframe loading=\"lazy\" class=\"pvfw-pdf-viewer-frame\" width=\"100%\" height=\"850\" src=\"https:\/\/greth.fr\/en\/themencode-pdf-viewer-sc\/?tnc_pvfw=ZmlsZT1odHRwczovL2dyZXRoLmZyL3B1YmxpYy9wdWJsaWNhdGlvbnMvMjAxOC8wMi8wMi5wZGYmc2V0dGluZ3M9MTExMTEwMTExMTExMTExMTEwMCZsYW5nPWZyLUZS#page=&#038;zoom=auto&#038;pagemode=\" title=\"\"><\/iframe>\n\n\n&nbsp;<br \/>\n\n<div class=\"eds-animate edsanimate-sis-hidden\" data-eds-entry-animation=\"bounceIn\" data-eds-entry-delay=\"0\" data-eds-entry-duration=\"1\" data-eds-entry-timing=\"linear\" data-eds-exit-animation=\"\" data-eds-exit-delay=\"\" data-eds-exit-duration=\"\" data-eds-exit-timing=\"\" data-eds-repeat-count=\"1\" data-eds-keep=\"yes\" data-eds-animate-on=\"load\" data-eds-scroll-offset=\"\">\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\n<p style=\"text-align: justify;\"><strong>&#x2666; The full version is only available for subscribers <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #3db2ea; color: #fff;\">\"ESSENTIEL\"<\/span><\/a> or <a style=\"text-decoration: none;\" href=\"\/en\/offre-du-greth\/\"><span style=\"background-color: #c6002c; color: #fff;\">\"PREMIUM\"<\/span><\/a> of GRETh!<\/strong><\/p>\n<p>&#x2666; If you are already a member \/ subscriber, you must identify yourself by <a href=\"\/wp-login.php\"><strong>clicking here<\/strong><\/a>.<br \/>\n&#x2666; If you are not a member, you can consult the offer proposed by GRETh by <a href=\"\/en\/offre-du-greth\/\"><strong>clicking here<\/strong><\/a> as well as the conditions of membership by <a href=\"\/en\/conditions-adhesion\/\"><strong>clicking here<\/strong><\/a>.\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; R\u00e9sum\u00e9 : Le pr\u00e9sent rapport technique est une \u00e9tude g\u00e9n\u00e9rale portant sur les m\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances dans le domaine des \u00e9changeurs de chaleur. L\u2019objectif de ce rapport est de pr\u00e9senter les diverses m\u00e9thodes et techniques de d\u00e9tection de d\u00e9faillances des \u00e9changeurs de chaleur. Ce document est \u00e0 mis \u00e0 &hellip;<\/p>","protected":false},"author":1,"featured_media":10338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,23],"tags":[6427,6430,6431,6428,6423,6424,6426,6429,6425],"class_list":["post-10335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents","category-rapports-techniques","tag-arbres-de-causes","tag-by-pass","tag-contact-thermique","tag-corrosion","tag-defaillance","tag-detection","tag-echangeur-thermique","tag-fuite","tag-symptome"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9changeurs de chaleur - M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances - GRETh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greth.fr\/en\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9changeurs de chaleur - M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; R\u00e9sum\u00e9 : Le pr\u00e9sent rapport technique est une \u00e9tude g\u00e9n\u00e9rale portant sur les m\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances dans le domaine des \u00e9changeurs de chaleur. L\u2019objectif de ce rapport est de pr\u00e9senter les diverses m\u00e9thodes et techniques de d\u00e9tection de d\u00e9faillances des \u00e9changeurs de chaleur. Ce document est \u00e0 mis \u00e0 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greth.fr\/en\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/\" \/>\n<meta property=\"og:site_name\" content=\"GRETh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/grethfr\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-05T14:12:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T14:32:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greth.fr\/wp-content\/uploads\/2018\/11\/Fotolia_191241529_S.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRETh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@grethfr\" \/>\n<meta name=\"twitter:site\" content=\"@grethfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRETh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/\"},\"author\":{\"name\":\"GRETh\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\"},\"headline\":\"\u00c9changeurs de chaleur &#8211; M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances\",\"datePublished\":\"2018-11-05T14:12:58+00:00\",\"dateModified\":\"2023-03-02T14:32:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/\"},\"wordCount\":895,\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Fotolia_191241529_S.jpg\",\"keywords\":[\"arbres de causes\",\"by-pass\",\"contact thermique\",\"corrosion\",\"d\u00e9faillance\",\"d\u00e9tection\",\"\u00e9changeur thermique\",\"fuite\",\"sympt\u00f4me\"],\"articleSection\":[\"Documents\",\"Rapports Techniques\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/\",\"name\":\"\u00c9changeurs de chaleur - M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances - GRETh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Fotolia_191241529_S.jpg\",\"datePublished\":\"2018-11-05T14:12:58+00:00\",\"dateModified\":\"2023-03-02T14:32:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Fotolia_191241529_S.jpg\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Fotolia_191241529_S.jpg\",\"width\":924,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greth.fr\\\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/greth.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9changeurs de chaleur &#8211; M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#website\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"name\":\"Groupement pour la Recherche sur les \u00c9changeurs Thermiques\",\"description\":\"Une structure qui f\u00e9d\u00e8re les industriels autour des \u00e9changeurs de chaleur et des syst\u00e8mes thermiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\"},\"alternateName\":\"GRETh\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greth.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#organization\",\"name\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\",\"alternateName\":\"GRETh\",\"url\":\"https:\\\/\\\/greth.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/maintenance.png\",\"width\":380,\"height\":460,\"caption\":\"Groupement pour la Recherche sur les Echangeurs Thermiques\"},\"image\":{\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/youtube.com\\\/c\\\/grethfrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/greth.fr\\\/#\\\/schema\\\/person\\\/6e173032c4ce46c14339ff999b721f00\",\"name\":\"GRETh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"url\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"contentUrl\":\"https:\\\/\\\/greth.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/avatar-greth-96x96.png\",\"caption\":\"GRETh\"},\"description\":\"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.\",\"sameAs\":[\"http:\\\/\\\/www.greth.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/grethfr\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greth\",\"https:\\\/\\\/x.com\\\/grethfr\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/grethfrance\"],\"url\":\"https:\\\/\\\/greth.fr\\\/en\\\/author\\\/greggus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9changeurs de chaleur - M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances - GRETh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greth.fr\/en\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/","og_locale":"en_US","og_type":"article","og_title":"\u00c9changeurs de chaleur - M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances","og_description":"&nbsp; R\u00e9sum\u00e9 : Le pr\u00e9sent rapport technique est une \u00e9tude g\u00e9n\u00e9rale portant sur les m\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances dans le domaine des \u00e9changeurs de chaleur. L\u2019objectif de ce rapport est de pr\u00e9senter les diverses m\u00e9thodes et techniques de d\u00e9tection de d\u00e9faillances des \u00e9changeurs de chaleur. Ce document est \u00e0 mis \u00e0 &hellip;","og_url":"https:\/\/greth.fr\/en\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/","og_site_name":"GRETh","article_publisher":"https:\/\/www.facebook.com\/grethfr\/","article_author":"https:\/\/www.facebook.com\/grethfr\/","article_published_time":"2018-11-05T14:12:58+00:00","article_modified_time":"2023-03-02T14:32:33+00:00","og_image":[{"width":924,"height":520,"url":"https:\/\/greth.fr\/wp-content\/uploads\/2018\/11\/Fotolia_191241529_S.jpg","type":"image\/jpeg"}],"author":"GRETh","twitter_card":"summary_large_image","twitter_creator":"@grethfr","twitter_site":"@grethfr","twitter_misc":{"Written by":"GRETh","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/#article","isPartOf":{"@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/"},"author":{"name":"GRETh","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00"},"headline":"\u00c9changeurs de chaleur &#8211; M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances","datePublished":"2018-11-05T14:12:58+00:00","dateModified":"2023-03-02T14:32:33+00:00","mainEntityOfPage":{"@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/"},"wordCount":895,"publisher":{"@id":"https:\/\/greth.fr\/#organization"},"image":{"@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2018\/11\/Fotolia_191241529_S.jpg","keywords":["arbres de causes","by-pass","contact thermique","corrosion","d\u00e9faillance","d\u00e9tection","\u00e9changeur thermique","fuite","sympt\u00f4me"],"articleSection":["Documents","Rapports Techniques"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/","url":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/","name":"\u00c9changeurs de chaleur - M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances - GRETh","isPartOf":{"@id":"https:\/\/greth.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/#primaryimage"},"image":{"@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/#primaryimage"},"thumbnailUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2018\/11\/Fotolia_191241529_S.jpg","datePublished":"2018-11-05T14:12:58+00:00","dateModified":"2023-03-02T14:32:33+00:00","breadcrumb":{"@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/#primaryimage","url":"https:\/\/greth.fr\/wp-content\/uploads\/2018\/11\/Fotolia_191241529_S.jpg","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2018\/11\/Fotolia_191241529_S.jpg","width":924,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/greth.fr\/echangeurs-de-chaleur-methodes-et-pratiques-de-la-detection-des-defaillances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/greth.fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9changeurs de chaleur &#8211; M\u00e9thodes et pratiques de la d\u00e9tection des d\u00e9faillances"}]},{"@type":"WebSite","@id":"https:\/\/greth.fr\/#website","url":"https:\/\/greth.fr\/","name":"Groupement pour la Recherche sur les \u00c9changeurs Thermiques","description":"A structure that brings together manufacturers around heat exchangers and thermal systems","publisher":{"@id":"https:\/\/greth.fr\/#organization"},"alternateName":"GRETh","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greth.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/greth.fr\/#organization","name":"Groupement pour la Recherche sur les Echangeurs Thermiques","alternateName":"GRETh","url":"https:\/\/greth.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/","url":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2019\/04\/maintenance.png","width":380,"height":460,"caption":"Groupement pour la Recherche sur les Echangeurs Thermiques"},"image":{"@id":"https:\/\/greth.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grethfr\/","https:\/\/x.com\/grethfr","https:\/\/www.linkedin.com\/company\/greth","https:\/\/youtube.com\/c\/grethfrance"]},{"@type":"Person","@id":"https:\/\/greth.fr\/#\/schema\/person\/6e173032c4ce46c14339ff999b721f00","name":"GRETh","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","url":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","contentUrl":"https:\/\/greth.fr\/wp-content\/uploads\/2023\/01\/avatar-greth-96x96.png","caption":"GRETh"},"description":"Le GRETh, f\u00e9d\u00e8re un collectif d'industriels dont l'activit\u00e9 est la fabrication d\u2019\u00e9changeurs et d\u2019\u00e9quipements thermiques, les \u00e9tudes d\u2019ing\u00e9nieries d\u2019installations thermiques pour l\u2019industrie et le b\u00e2timent ainsi que l\u2019exploitation de sites de production et de conversion d\u2019\u00e9nergie.","sameAs":["http:\/\/www.greth.fr\/","https:\/\/www.facebook.com\/grethfr\/","https:\/\/www.linkedin.com\/company\/greth","https:\/\/x.com\/grethfr","https:\/\/www.youtube.com\/c\/grethfrance"],"url":"https:\/\/greth.fr\/en\/author\/greggus\/"}]}},"_links":{"self":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/10335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/comments?post=10335"}],"version-history":[{"count":0,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/posts\/10335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media\/10338"}],"wp:attachment":[{"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/media?parent=10335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/categories?post=10335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greth.fr\/en\/wp-json\/wp\/v2\/tags?post=10335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}